{"id":30826,"date":"2023-09-15T22:34:07","date_gmt":"2023-09-15T22:34:07","guid":{"rendered":"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/"},"modified":"2023-09-15T22:34:07","modified_gmt":"2023-09-15T22:34:07","slug":"sb0101011","status":"publish","type":"product","link":"https:\/\/ricambi.officinefvg.it\/en\/negozio\/sb0101011\/","title":{"rendered":"SB0101011"},"content":{"rendered":"<p>STRAIGHT TERMINAL T6X1 M10X1<\/p>","protected":false},"excerpt":{"rendered":"<p>STRAIGHT TERMINAL T6X1 M10X1<\/p>","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[],"product_tag":[],"class_list":["post-30826","product","type-product","status-publish","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Codice ricambio: SB0101011 - Magazzino Officine FVG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ricambi.officinefvg.it\/en\/negozio\/sb0101011\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Codice ricambio: SB0101011 - Magazzino Officine FVG\" \/>\n<meta property=\"og:description\" content=\"TERMINALE DIRITTO T6X1 M10X1\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ricambi.officinefvg.it\/en\/negozio\/sb0101011\/\" \/>\n<meta property=\"og:site_name\" content=\"Ricambi - OfficineFVG\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/\",\"url\":\"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/\",\"name\":\"Codice ricambio: SB0101011 - Magazzino Officine FVG\",\"isPartOf\":{\"@id\":\"https:\/\/ricambi.officinefvg.it\/#website\"},\"datePublished\":\"2023-09-15T22:34:07+00:00\",\"dateModified\":\"2023-09-15T22:34:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ricambi.officinefvg.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Negozio\",\"item\":\"https:\/\/ricambi.officinefvg.it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SB0101011\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ricambi.officinefvg.it\/#website\",\"url\":\"https:\/\/ricambi.officinefvg.it\/\",\"name\":\"Ricambi Online - OfficineFVG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/ricambi.officinefvg.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ricambi.officinefvg.it\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ricambi.officinefvg.it\/#organization\",\"name\":\"OfficineFVG\",\"url\":\"https:\/\/ricambi.officinefvg.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/ricambi.officinefvg.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ricambi.officinefvg.it\/wp-content\/uploads\/ofvg.png\",\"contentUrl\":\"https:\/\/ricambi.officinefvg.it\/wp-content\/uploads\/ofvg.png\",\"width\":640,\"height\":193,\"caption\":\"OfficineFVG\"},\"image\":{\"@id\":\"https:\/\/ricambi.officinefvg.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Codice ricambio: SB0101011 - Magazzino Officine FVG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ricambi.officinefvg.it\/en\/negozio\/sb0101011\/","og_locale":"en_GB","og_type":"article","og_title":"Codice ricambio: SB0101011 - Magazzino Officine FVG","og_description":"TERMINALE DIRITTO T6X1 M10X1","og_url":"https:\/\/ricambi.officinefvg.it\/en\/negozio\/sb0101011\/","og_site_name":"Ricambi - OfficineFVG","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/","url":"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/","name":"Codice ricambio: SB0101011 - Magazzino Officine FVG","isPartOf":{"@id":"https:\/\/ricambi.officinefvg.it\/#website"},"datePublished":"2023-09-15T22:34:07+00:00","dateModified":"2023-09-15T22:34:07+00:00","breadcrumb":{"@id":"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ricambi.officinefvg.it\/negozio\/sb0101011\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ricambi.officinefvg.it\/"},{"@type":"ListItem","position":2,"name":"Negozio","item":"https:\/\/ricambi.officinefvg.it\/negozio\/"},{"@type":"ListItem","position":3,"name":"SB0101011"}]},{"@type":"WebSite","@id":"https:\/\/ricambi.officinefvg.it\/#website","url":"https:\/\/ricambi.officinefvg.it\/","name":"Ricambi Online - OfficineFVG","description":"","publisher":{"@id":"https:\/\/ricambi.officinefvg.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ricambi.officinefvg.it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ricambi.officinefvg.it\/#organization","name":"OfficineFVG","url":"https:\/\/ricambi.officinefvg.it\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ricambi.officinefvg.it\/#\/schema\/logo\/image\/","url":"https:\/\/ricambi.officinefvg.it\/wp-content\/uploads\/ofvg.png","contentUrl":"https:\/\/ricambi.officinefvg.it\/wp-content\/uploads\/ofvg.png","width":640,"height":193,"caption":"OfficineFVG"},"image":{"@id":"https:\/\/ricambi.officinefvg.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ricambi.officinefvg.it\/en\/wp-json\/wp\/v2\/product\/30826","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ricambi.officinefvg.it\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ricambi.officinefvg.it\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/ricambi.officinefvg.it\/en\/wp-json\/wp\/v2\/comments?post=30826"}],"wp:attachment":[{"href":"https:\/\/ricambi.officinefvg.it\/en\/wp-json\/wp\/v2\/media?parent=30826"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ricambi.officinefvg.it\/en\/wp-json\/wp\/v2\/product_cat?post=30826"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ricambi.officinefvg.it\/en\/wp-json\/wp\/v2\/product_tag?post=30826"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}